{"id":13833,"date":"2025-02-24T22:45:25","date_gmt":"2025-02-24T21:45:25","guid":{"rendered":"https:\/\/stage.staviori.com.pl\/product\/kolczyk-z-brylantami-kbd5720\/"},"modified":"2026-02-11T00:08:34","modified_gmt":"2026-02-10T23:08:34","slug":"kolczyk-z-brylantami-kbd5720","status":"publish","type":"product","link":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/","title":{"rendered":"Ohrringe aus Wei\u00dfgold mit Diamanten - KBD5720"},"content":{"rendered":"<p>Model: KBD5720<br \/>\nWaga ok. 0,84g<\/p>\n<p>Ohrringe.<br \/>\nWei\u00dfgold 0,585.<br \/>\n2 Diamenty, szlif brylantowy, o masie 0,08ct, barwa H, czysto\u015b\u0107 SI1-SI2.<\/p>\n<p>L\u00e4nge 9 mm.<br \/>\n4 mm breit.<\/p>\n<p>Dost\u0119pne r\u00f3wnie\u017c w \u017c\u00f3\u0142tym z\u0142ocie pod symbolem: KZD5720<\/p>","protected":false},"excerpt":{"rendered":"<p>Subtelne i pe\u0142ne wdzi\u0119ku kolczyki z bia\u0142ego z\u0142ota pr\u00f3by 0,585 zachwycaj\u0105 nowoczesnym wzornictwem i ponadczasow\u0105 elegancj\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\u0142ota dodaj\u0105 im blasku i lekko\u015bci. Ich kompaktowa forma sprawia, \u017ce idealnie nadaj\u0105 si\u0119 na co dzie\u0144, jak i na wyj\u0105tkowe okazje. To bi\u017cuteria, kt\u00f3ra podkre\u015bla kobiec\u0105 klas\u0119 i wyczucie stylu.<\/p>","protected":false},"featured_media":1704,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false},"product_brand":[2284],"product_cat":[1838,199,1990,2044,1930],"product_tag":[2308,2317,2918,2603,1394,2665,2667,2291],"class_list":["post-13833","product","type-product","status-publish","has-post-thumbnail","product_brand-staviori","product_cat-diamenty","product_cat-kolczyki","product_cat-kolczyk-z-brylantami","product_cat-zlote-kolczyki","product_cat-zloto","product_tag-biale-zloto","product_tag-elegancka-bizuteria","product_tag-kbd5720","product_tag-klasyczna-bizuteria","product_tag-kolczyki","product_tag-kolczyki-sztyfty","product_tag-kolczyki-z-diamentami","product_tag-prezent-dla-niej","pa_barwa-h-2","pa_czystosc-si1","pa_dlugosc-9mm","pa_dostawca-estrella","pa_kamien-diament","pa_kolor-biale","pa_kruszec-zloto","pa_proba-0-585","pa_szerokosc-4mm","pa_waga-075g","pa_zapiecie-sztyft","first","instock","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Subtelne i pe\u0142ne wdzi\u0119ku kolczyki z bia\u0142ego z\u0142ota pr\u00f3by 0,585 zachwycaj\u0105 nowoczesnym wzornictwem i ponadczasow\u0105 elegancj\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\u0142ota dodaj\u0105 im blasku i lekko\u015bci. Ich kompaktowa forma sprawia, \u017ce idealnie nadaj\u0105 si\u0119 na co dzie\u0144, jak i na wyj\u0105tkowe okazje. To bi\u017cuteria, kt\u00f3ra podkre\u015bla kobiec\u0105 klas\u0119 i wyczucie stylu.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"iGGPvpWDjZN1_r6YkwnutzmmQsvPyvuVoKdFILjCIto\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Staviori - Pier\u015bcionek Zar\u0119czynowy z Brylantem, Diamentem, Szafirem...\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kolczyki z bia\u0142ego z\u0142ota z diamentami \u2013 KBD5720 - Staviori\" \/>\n\t\t<meta property=\"og:description\" content=\"Subtelne i pe\u0142ne wdzi\u0119ku kolczyki z bia\u0142ego z\u0142ota pr\u00f3by 0,585 zachwycaj\u0105 nowoczesnym wzornictwem i ponadczasow\u0105 elegancj\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\u0142ota dodaj\u0105 im blasku i lekko\u015bci. Ich kompaktowa forma sprawia, \u017ce idealnie nadaj\u0105 si\u0119 na co dzie\u0144, jak i na wyj\u0105tkowe okazje. To bi\u017cuteria, kt\u00f3ra podkre\u015bla kobiec\u0105 klas\u0119 i wyczucie stylu.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-02-24T21:45:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-10T23:08:34+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kolczyki z bia\u0142ego z\u0142ota z diamentami \u2013 KBD5720 - Staviori\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Subtelne i pe\u0142ne wdzi\u0119ku kolczyki z bia\u0142ego z\u0142ota pr\u00f3by 0,585 zachwycaj\u0105 nowoczesnym wzornictwem i ponadczasow\u0105 elegancj\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\u0142ota dodaj\u0105 im blasku i lekko\u015bci. Ich kompaktowa forma sprawia, \u017ce idealnie nadaj\u0105 si\u0119 na co dzie\u0144, jak i na wyj\u0105tkowe okazje. To bi\u017cuteria, kt\u00f3ra podkre\u015bla kobiec\u0105 klas\u0119 i wyczucie stylu.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/product\\\/kolczyk-z-brylantami-kbd5720\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staviori.pl\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/sklep\\\/#listItem\",\"name\":\"Sklep\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/sklep\\\/#listItem\",\"position\":2,\"name\":\"Sklep\",\"item\":\"https:\\\/\\\/staviori.pl\\\/de\\\/sklep\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/Marke\\\/staviori\\\/#listItem\",\"name\":\"Staviori\\u00ae\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/Marke\\\/staviori\\\/#listItem\",\"position\":3,\"name\":\"Staviori\\u00ae\",\"item\":\"https:\\\/\\\/staviori.pl\\\/de\\\/Marke\\\/staviori\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/product\\\/kolczyk-z-brylantami-kbd5720\\\/#listItem\",\"name\":\"Kolczyki z bia\\u0142ego z\\u0142ota z diamentami &#8211; KBD5720\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/sklep\\\/#listItem\",\"name\":\"Sklep\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/product\\\/kolczyk-z-brylantami-kbd5720\\\/#listItem\",\"position\":4,\"name\":\"Kolczyki z bia\\u0142ego z\\u0142ota z diamentami &#8211; KBD5720\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/Marke\\\/staviori\\\/#listItem\",\"name\":\"Staviori\\u00ae\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/product\\\/kolczyk-z-brylantami-kbd5720\\\/#itempage\",\"url\":\"https:\\\/\\\/staviori.pl\\\/de\\\/product\\\/kolczyk-z-brylantami-kbd5720\\\/\",\"name\":\"Kolczyki z bia\\u0142ego z\\u0142ota z diamentami \\u2013 KBD5720 - Staviori\",\"description\":\"Subtelne i pe\\u0142ne wdzi\\u0119ku kolczyki z bia\\u0142ego z\\u0142ota pr\\u00f3by 0,585 zachwycaj\\u0105 nowoczesnym wzornictwem i ponadczasow\\u0105 elegancj\\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\\u0142ota dodaj\\u0105 im blasku i lekko\\u015bci. Ich kompaktowa forma sprawia, \\u017ce idealnie nadaj\\u0105 si\\u0119 na co dzie\\u0144, jak i na wyj\\u0105tkowe okazje. To bi\\u017cuteria, kt\\u00f3ra podkre\\u015bla kobiec\\u0105 klas\\u0119 i wyczucie stylu.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/product\\\/kolczyk-z-brylantami-kbd5720\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/staviori.pl\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/5966.jpg\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/product\\\/kolczyk-z-brylantami-kbd5720\\\/#mainImage\",\"width\":600,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/product\\\/kolczyk-z-brylantami-kbd5720\\\/#mainImage\"},\"datePublished\":\"2025-02-24T22:45:25+01:00\",\"dateModified\":\"2026-02-11T00:08:34+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/#organization\",\"name\":\"Staviori\",\"description\":\"Pier\\u015bcionek Zar\\u0119czynowy z Brylantem, Diamentem, Szafirem...\",\"url\":\"https:\\\/\\\/staviori.pl\\\/de\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/staviori.pl\\\/de\\\/\",\"name\":\"Staviori\",\"description\":\"Pier\\u015bcionek Zar\\u0119czynowy z Brylantem, Diamentem, Szafirem...\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kolczyki z bia\u0142ego z\u0142ota z diamentami \u2013 KBD5720 - Staviori","description":"Subtelne i pe\u0142ne wdzi\u0119ku kolczyki z bia\u0142ego z\u0142ota pr\u00f3by 0,585 zachwycaj\u0105 nowoczesnym wzornictwem i ponadczasow\u0105 elegancj\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\u0142ota dodaj\u0105 im blasku i lekko\u015bci. Ich kompaktowa forma sprawia, \u017ce idealnie nadaj\u0105 si\u0119 na co dzie\u0144, jak i na wyj\u0105tkowe okazje. To bi\u017cuteria, kt\u00f3ra podkre\u015bla kobiec\u0105 klas\u0119 i wyczucie stylu.","canonical_url":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"iGGPvpWDjZN1_r6YkwnutzmmQsvPyvuVoKdFILjCIto","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de#listItem","position":1,"name":"Home","item":"https:\/\/staviori.pl\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/sklep\/#listItem","name":"Sklep"}},{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/sklep\/#listItem","position":2,"name":"Sklep","item":"https:\/\/staviori.pl\/de\/sklep\/","nextItem":{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/Marke\/staviori\/#listItem","name":"Staviori\u00ae"},"previousItem":{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/Marke\/staviori\/#listItem","position":3,"name":"Staviori\u00ae","item":"https:\/\/staviori.pl\/de\/Marke\/staviori\/","nextItem":{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/#listItem","name":"Kolczyki z bia\u0142ego z\u0142ota z diamentami &#8211; KBD5720"},"previousItem":{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/sklep\/#listItem","name":"Sklep"}},{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/#listItem","position":4,"name":"Kolczyki z bia\u0142ego z\u0142ota z diamentami &#8211; KBD5720","previousItem":{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/Marke\/staviori\/#listItem","name":"Staviori\u00ae"}}]},{"@type":"ItemPage","@id":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/#itempage","url":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/","name":"Kolczyki z bia\u0142ego z\u0142ota z diamentami \u2013 KBD5720 - Staviori","description":"Subtelne i pe\u0142ne wdzi\u0119ku kolczyki z bia\u0142ego z\u0142ota pr\u00f3by 0,585 zachwycaj\u0105 nowoczesnym wzornictwem i ponadczasow\u0105 elegancj\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\u0142ota dodaj\u0105 im blasku i lekko\u015bci. Ich kompaktowa forma sprawia, \u017ce idealnie nadaj\u0105 si\u0119 na co dzie\u0144, jak i na wyj\u0105tkowe okazje. To bi\u017cuteria, kt\u00f3ra podkre\u015bla kobiec\u0105 klas\u0119 i wyczucie stylu.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/staviori.pl\/de\/#website"},"breadcrumb":{"@id":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/staviori.pl\/wp-content\/uploads\/2023\/04\/5966.jpg","@id":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/#mainImage","width":600,"height":600},"primaryImageOfPage":{"@id":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/#mainImage"},"datePublished":"2025-02-24T22:45:25+01:00","dateModified":"2026-02-11T00:08:34+01:00"},{"@type":"Organization","@id":"https:\/\/staviori.pl\/de\/#organization","name":"Staviori","description":"Pier\u015bcionek Zar\u0119czynowy z Brylantem, Diamentem, Szafirem...","url":"https:\/\/staviori.pl\/de\/"},{"@type":"WebSite","@id":"https:\/\/staviori.pl\/de\/#website","url":"https:\/\/staviori.pl\/de\/","name":"Staviori","description":"Pier\u015bcionek Zar\u0119czynowy z Brylantem, Diamentem, Szafirem...","inLanguage":"de-DE","publisher":{"@id":"https:\/\/staviori.pl\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Staviori - Pier\u015bcionek Zar\u0119czynowy z Brylantem, Diamentem, Szafirem...","og:type":"article","og:title":"Kolczyki z bia\u0142ego z\u0142ota z diamentami \u2013 KBD5720 - Staviori","og:description":"Subtelne i pe\u0142ne wdzi\u0119ku kolczyki z bia\u0142ego z\u0142ota pr\u00f3by 0,585 zachwycaj\u0105 nowoczesnym wzornictwem i ponadczasow\u0105 elegancj\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\u0142ota dodaj\u0105 im blasku i lekko\u015bci. Ich kompaktowa forma sprawia, \u017ce idealnie nadaj\u0105 si\u0119 na co dzie\u0144, jak i na wyj\u0105tkowe okazje. To bi\u017cuteria, kt\u00f3ra podkre\u015bla kobiec\u0105 klas\u0119 i wyczucie stylu.","og:url":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/","article:published_time":"2025-02-24T21:45:25+00:00","article:modified_time":"2026-02-10T23:08:34+00:00","twitter:card":"summary_large_image","twitter:title":"Kolczyki z bia\u0142ego z\u0142ota z diamentami \u2013 KBD5720 - Staviori","twitter:description":"Subtelne i pe\u0142ne wdzi\u0119ku kolczyki z bia\u0142ego z\u0142ota pr\u00f3by 0,585 zachwycaj\u0105 nowoczesnym wzornictwem i ponadczasow\u0105 elegancj\u0105. Diamenty o szlifie brylantowym delikatnie zatopione w spiralnym oplocie z\u0142ota dodaj\u0105 im blasku i lekko\u015bci. Ich kompaktowa forma sprawia, \u017ce idealnie nadaj\u0105 si\u0119 na co dzie\u0144, jak i na wyj\u0105tkowe okazje. To bi\u017cuteria, kt\u00f3ra podkre\u015bla kobiec\u0105 klas\u0119 i wyczucie stylu."},"aioseo_meta_data":{"post_id":"13833","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"kolczyki z bia\u0142ego z\u0142ota z diamentami","score":44,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":6,"maxScore":9,"error":1,"length":8},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":true,"ai":null,"created":"2025-02-26 12:25:09","updated":"2026-02-10 23:47:41","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/staviori.pl\/de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/staviori.pl\/de\/sklep\/\" title=\"Sklep\">Sklep<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/staviori.pl\/de\/Marke\/staviori\/\" title=\"Staviori\u00ae\">Staviori\u00ae<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKolczyki z bia\u0142ego z\u0142ota z diamentami \u2013 KBD5720\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/staviori.pl\/de"},{"label":"Sklep","link":"https:\/\/staviori.pl\/de\/sklep\/"},{"label":"Staviori\u00ae","link":"https:\/\/staviori.pl\/de\/Marke\/staviori\/"},{"label":"Kolczyki z bia\u0142ego z\u0142ota z diamentami &#8211; KBD5720","link":"https:\/\/staviori.pl\/de\/product\/kolczyk-z-brylantami-kbd5720\/"}],"_links":{"self":[{"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/product\/13833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/comments?post=13833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/media\/1704"}],"wp:attachment":[{"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/media?parent=13833"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/product_brand?post=13833"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/product_cat?post=13833"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/product_tag?post=13833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}