{"id":9329,"date":"2023-04-26T19:43:55","date_gmt":"2023-04-26T17:43:55","guid":{"rendered":"https:\/\/stage.staviori.com.pl\/?page_id=9329"},"modified":"2026-01-21T12:45:33","modified_gmt":"2026-01-21T11:45:33","slug":"regulamin","status":"publish","type":"page","link":"https:\/\/staviori.pl\/de\/regulamin\/","title":{"rendered":"Verordnungen"},"content":{"rendered":"<section class=\"section\" id=\"section_244881354\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-1707613154\">\n\n\n\t<div id=\"col-45648504\" class=\"col medium-11 small-12 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Verordnungen<\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n\t<div id=\"text-3284599391\" class=\"text\">\n\t\t\n\n<div class=\"pyt\">\n<h3>\u00a7 I - Vorbemerkungen<\/h3>\n<ol>\n<li>Diese Bedingungen wurden in \u00dcbereinstimmung mit dem Gesetz \u00fcber elektronische Dienstleistungen und dem Gesetz \u00fcber Verbraucherrechte erstellt und legen die Regeln f\u00fcr die Nutzung von staviori.com.pl fest.\u00a0<\/li>\n<\/ol>\n<ol start=\"2\">\n<li>Der Dienstanbieter und Verk\u00e4ufer ist INFINITY Dawid Namy\u015blak, ul. Jeleniog\u00f3rska 16, 60-179 Pozna\u0144, NIP 7772573745, REGON 301254472.<\/li>\n<\/ol>\n<ol start=\"3\">\n<li>In den Allgemeinen Gesch\u00e4ftsbedingungen sind die Regeln f\u00fcr die Erstellung eines Kontos, die Aufgabe von Bestellungen, den Abschluss von Vertr\u00e4gen und die Erbringung von Dienstleistungen \u00fcber die Website festgelegt.<\/li>\n<\/ol>\n<ol start=\"4\">\n<li>Die Marken von Staviori\u00ae sind gesetzlich gesch\u00fctzt und ihre Verwendung ohne Genehmigung ist verboten.<\/li>\n<\/ol>\n<h3>\u00a7 II - Begriffsbestimmungen<\/h3>\n<p>1. account - Funktionalit\u00e4t zur Verwaltung von Daten und Bestellhistorie.<\/p>\n<p>(2) Vorschriften - diese Regeln und Vorschriften f\u00fcr die Erbringung von Dienstleistungen.<\/p>\n<p>3. Service - die Website unter staviori.com.pl<\/p>\n<p>4 Unternehmen - INFINITY Dawid Namy\u015blak mit Sitz in Pozna\u0144.<\/p>\n<p>5. Nutzer\/Kunde - die Person, die den Dienst nutzt.<\/p>\n<p>6. Partner - ein Unternehmen, das mit staviori auf der Basis einer kommerziellen Zusammenarbeit ( b2b ) kooperiert und mit dem das Unternehmen einen separaten Vertriebsvertrag abgeschlossen hat.<\/p>\n<h3>\u00a7 III - Kontof\u00fchrung<\/h3>\n<p>1. Die Einrichtung eines Kontos ist freiwillig und nicht notwendig oder erforderlich, um einen Kauf zu t\u00e4tigen.<\/p>\n<p>2 Die Verarbeitung personenbezogener Daten erfolgt in \u00dcbereinstimmung mit der RODO und der Datenschutzrichtlinie.<\/p>\n<p>(3) Einige Funktionen k\u00f6nnen zus\u00e4tzliche Daten erfordern.<\/p>\n<p>4 Verwalter der personenbezogenen Daten, die der Kunde im Zusammenhang mit der Absendung der Bestellung zum Zwecke des Abschlusses und der Erf\u00fcllung des Kaufvertrages angibt, ist INFINITY Dawid Namyslak. Der Kunde hat das Recht, auf den Inhalt seiner Daten zuzugreifen und diese zu korrigieren und zu aktualisieren. Die Angabe der Daten ist freiwillig, aber f\u00fcr die \u00dcbermittlung der Bestellung und f\u00fcr den Abschluss und die Erf\u00fcllung des Kaufvertrags notwendig. Die personenbezogenen Daten des Kunden werden gem\u00e4\u00df den Grunds\u00e4tzen des Gesetzes vom 29. August 1997 \u00fcber den Schutz personenbezogener Daten (GBl. 2014, Pos. 1182, in der ge\u00e4nderten Fassung) zum Zwecke des Abschlusses und der Erf\u00fcllung des Kaufvertrags verarbeitet und k\u00f6nnen zum Zwecke der Vertragserf\u00fcllung anderen Unternehmen zur Verf\u00fcgung gestellt werden, d.h. Unternehmen, die INFINITY Dawid Namy\u015blak Dienstleistungen im Bereich des Warenversands oder der Einziehung und Durchsetzung von Forderungen im Zusammenhang mit dem Vertrag erbringen.<\/p>\n<p>5 Die Website verwendet Cookies in \u00dcbereinstimmung mit der Cookie-Richtlinie.<\/p>\n<h3>\u00a7 IV - Mitteilungen<\/h3>\n<p>1 Sie erhalten eine Benachrichtigung \u00fcber die Fertigstellung Ihrer Bestellung per E-Mail oder per Telefon.<\/p>\n<p>2 Benachrichtigungen sind transaktionaler Natur und erfordern keine zus\u00e4tzliche Zustimmung zur Vermarktung.<\/p>\n<h3>\u00a7 V - Daten\u00fcberpr\u00fcfungen<\/h3>\n<p>1 Um den Dienst nutzen zu k\u00f6nnen, kann es notwendig sein, Ihre E-Mail-Adresse zu verifizieren, indem Sie den Aktivierungslink best\u00e4tigen.<\/p>\n<p>2. Die Telefonverifizierung kann per SMS-Code erfolgen.<\/p>\n<p>(3) Die Allgemeinen Gesch\u00e4ftsbedingungen der einzelnen \u00fcber die Website verf\u00fcgbaren Dienste k\u00f6nnen andere Arten der \u00dcberpr\u00fcfung vorsehen.<\/p>\n<h3>\u00a7 VI - Personenbezogene Daten<\/h3>\n<p>1 Der Inhaber der personenbezogenen Daten ist das Unternehmen.<\/p>\n<p>2 Die Grunds\u00e4tze der Datenverarbeitung sind in der Datenschutzrichtlinie dargelegt, die mit der RODO \u00fcbereinstimmt.<\/p>\n<p>3 Die Angabe von Daten ist freiwillig, aber f\u00fcr die Ausf\u00fchrung des Auftrags notwendig.<\/p>\n<p>4 Der Nutzer kann den DSB unter der E-Mail-Adresse dawid@staviori.pl kontaktieren.<\/p>\n<h3>\u00a7 VII - Erg\u00e4nzende Produkte und Dienstleistungen<\/h3>\n<p>Die auf der Website und in den Katalogen angegebenen Gewichte und Abmessungen der Produkte sind Richtwerte und k\u00f6nnen aufgrund ihrer physikalischen Eigenschaften von den Gewichten und Abmessungen der an den Kunden gelieferten Produkte abweichen.<\/p>\n<p>(2) Der Inhalt der Kataloge www.staviori.com.pl stellt kein Angebot im Sinne des B\u00fcrgerlichen Gesetzbuches dar.<\/p>\n<p>(3) Alle Preise sind Bruttopreise, unabh\u00e4ngig davon, ob sie auf polnische Zloty oder andere W\u00e4hrungen lauten, und enthalten die polnische Mehrwertsteuer.<\/p>\n<p>(4) Die Gesellschaft kann in \u00dcbereinstimmung mit dem Omnibus Preise \u00e4ndern und Werbeaktionen durchf\u00fchren.<\/p>\n<p>(5) Alle auf der Website angebotenen Produkte sind fabrikneu, frei von Sach- und Rechtsm\u00e4ngeln und wurden in der Europ\u00e4ischen Union rechtm\u00e4\u00dfig in Verkehr gebracht.<\/p>\n<p>(6) Das Konto erm\u00f6glicht es dem Nutzer, zus\u00e4tzliche Dienste in Anspruch zu nehmen, einschlie\u00dflich der von Dritten \u00fcber die Website angebotenen Dienste.<\/p>\n<p>7 Zus\u00e4tzliche Dienstleistungen k\u00f6nnen vom Nutzer \u00fcber die Website bestellt werden.<\/p>\n<p>(8) Als Teil Ihres Kontos haben Sie Zugang zu Informationen \u00fcber die zus\u00e4tzlichen Dienste, die Sie \u00fcber den Dienst nutzen, und k\u00f6nnen vom Unternehmen Benachrichtigungen und Mitteilungen \u00fcber diese Dienste erhalten.<\/p>\n<p>(9) Detaillierte Regeln f\u00fcr Zusatzdienste sind in ihren Verordnungen festgelegt.<\/p>\n<h3>\u00a7 VII a \u2013 Dostawa Towar\u00f3w<\/h3>\n<ol class=\"marker:text-quiet list-decimal\">\n<li class=\"py-0 my-0 prose-p:pt-0 prose-p:mb-2 prose-p:my-0 &#091;&amp;&gt;p&#093;:pt-0 &#091;&amp;&gt;p&#093;:mb-2 &#091;&amp;&gt;p&#093;:my-0\" style=\"box-sizing: border-box; scrollbar-color: initial; scrollbar-width: initial; --tw-border-spacing-x: 0; --tw-border-spacing-y: 0; --tw-translate-x: 0; --tw-translate-y: 0; --tw-rotate: 0; --tw-skew-x: 0; --tw-skew-y: 0; --tw-scale-x: 1; --tw-scale-y: 1; --tw-scroll-snap-strictness: proximity; --tw-ring-offset-width: 0px; --tw-ring-offset-color: #fff; --tw-ring-color: rgb(59 130 246 \/ .5); --tw-ring-offset-shadow: 0 0 #0000; --tw-ring-shadow: 0 0 #0000; --tw-shadow: 0 0 #0000; --tw-shadow-colored: 0 0 #0000; margin-top: 0px; margin-bottom: 0px; padding-inline-start: 0.375em; padding-top: 0px; padding-bottom: 0px; border: 0px solid oklch(var(--foreground-subtler-color));\">\n<p class=\"my-2 &#091;&amp;+p&#093;:mt-4 &#091;&amp;_strong:has(+br)&#093;:inline-block &#091;&amp;_strong:has(+br)&#093;:pb-2\">Dostawa Produkt\u00f3w odbywa si\u0119 na terytorium Rzeczypospolitej Polskiej oraz innych kraj\u00f3w wskazanych w Serwisie, za po\u015brednictwem firm kurierskich, operatora pocztowego lub do paczkomat\u00f3w \/ punkt\u00f3w odbioru, zgodnie z aktualnie dost\u0119pnymi opcjami dostawy prezentowanymi w trakcie sk\u0142adania zam\u00f3wienia.<\/p>\n<\/li>\n<li class=\"py-0 my-0 prose-p:pt-0 prose-p:mb-2 prose-p:my-0 &#091;&amp;&gt;p&#093;:pt-0 &#091;&amp;&gt;p&#093;:mb-2 &#091;&amp;&gt;p&#093;:my-0\" style=\"box-sizing: border-box; scrollbar-color: initial; scrollbar-width: initial; --tw-border-spacing-x: 0; --tw-border-spacing-y: 0; --tw-translate-x: 0; --tw-translate-y: 0; --tw-rotate: 0; --tw-skew-x: 0; --tw-skew-y: 0; --tw-scale-x: 1; --tw-scale-y: 1; --tw-scroll-snap-strictness: proximity; --tw-ring-offset-width: 0px; --tw-ring-offset-color: #fff; --tw-ring-color: rgb(59 130 246 \/ .5); --tw-ring-offset-shadow: 0 0 #0000; --tw-ring-shadow: 0 0 #0000; --tw-shadow: 0 0 #0000; --tw-shadow-colored: 0 0 #0000; margin-top: 0px; margin-bottom: 0px; padding-inline-start: 0.375em; padding-top: 0px; padding-bottom: 0px; border: 0px solid oklch(var(--foreground-subtler-color));\">\n<p class=\"my-2 &#091;&amp;+p&#093;:mt-4 &#091;&amp;_strong:has(+br)&#093;:inline-block &#091;&amp;_strong:has(+br)&#093;:pb-2\">Szczeg\u00f3\u0142owe informacje dotycz\u0105ce dost\u0119pnych sposob\u00f3w dostawy, przewidywanego czasu dostawy oraz aktualnych koszt\u00f3w dostawy znajduj\u0105 si\u0119 w zak\u0142adce \u201eKoszt dostawy\/Czas dostawy&#8221;.<\/p>\n<\/li>\n<li class=\"py-0 my-0 prose-p:pt-0 prose-p:mb-2 prose-p:my-0 &#091;&amp;&gt;p&#093;:pt-0 &#091;&amp;&gt;p&#093;:mb-2 &#091;&amp;&gt;p&#093;:my-0\" style=\"box-sizing: border-box; scrollbar-color: initial; scrollbar-width: initial; --tw-border-spacing-x: 0; --tw-border-spacing-y: 0; --tw-translate-x: 0; --tw-translate-y: 0; --tw-rotate: 0; --tw-skew-x: 0; --tw-skew-y: 0; --tw-scale-x: 1; --tw-scale-y: 1; --tw-scroll-snap-strictness: proximity; --tw-ring-offset-width: 0px; --tw-ring-offset-color: #fff; --tw-ring-color: rgb(59 130 246 \/ .5); --tw-ring-offset-shadow: 0 0 #0000; --tw-ring-shadow: 0 0 #0000; --tw-shadow: 0 0 #0000; --tw-shadow-colored: 0 0 #0000; margin-top: 0px; margin-bottom: 0px; padding-inline-start: 0.375em; padding-top: 0px; padding-bottom: 0px; border: 0px solid oklch(var(--foreground-subtler-color));\">\n<p class=\"my-2 &#091;&amp;+p&#093;:mt-4 &#091;&amp;_strong:has(+br)&#093;:inline-block &#091;&amp;_strong:has(+br)&#093;:pb-2\">Koszty dostawy s\u0105 r\u00f3wnie\u017c ka\u017cdorazowo wskazywane Klientowi przed z\u0142o\u017ceniem zam\u00f3wienia, w tym na etapie dodawania Produkt\u00f3w do koszyka oraz w podsumowaniu zam\u00f3wienia.<\/p>\n<\/li>\n<li class=\"py-0 my-0 prose-p:pt-0 prose-p:mb-2 prose-p:my-0 &#091;&amp;&gt;p&#093;:pt-0 &#091;&amp;&gt;p&#093;:mb-2 &#091;&amp;&gt;p&#093;:my-0\" style=\"box-sizing: border-box; scrollbar-color: initial; scrollbar-width: initial; --tw-border-spacing-x: 0; --tw-border-spacing-y: 0; --tw-translate-x: 0; --tw-translate-y: 0; --tw-rotate: 0; --tw-skew-x: 0; --tw-skew-y: 0; --tw-scale-x: 1; --tw-scale-y: 1; --tw-scroll-snap-strictness: proximity; --tw-ring-offset-width: 0px; --tw-ring-offset-color: #fff; --tw-ring-color: rgb(59 130 246 \/ .5); --tw-ring-offset-shadow: 0 0 #0000; --tw-ring-shadow: 0 0 #0000; --tw-shadow: 0 0 #0000; --tw-shadow-colored: 0 0 #0000; margin-top: 0px; margin-bottom: 0px; padding-inline-start: 0.375em; padding-top: 0px; padding-bottom: 0px; border: 0px solid oklch(var(--foreground-subtler-color));\">\n<p class=\"my-2 &#091;&amp;+p&#093;:mt-4 &#091;&amp;_strong:has(+br)&#093;:inline-block &#091;&amp;_strong:has(+br)&#093;:pb-2\">Termin realizacji zam\u00f3wienia liczony jest od dnia zaksi\u0119gowania p\u0142atno\u015bci lub pozytywnej autoryzacji p\u0142atno\u015bci elektronicznej, chyba \u017ce Klient wybra\u0142 opcj\u0119 p\u0142atno\u015bci za pobraniem \u2013 w takim przypadku termin liczony jest od dnia zawarcia umowy sprzeda\u017cy.<\/p>\n<\/li>\n<li class=\"py-0 my-0 prose-p:pt-0 prose-p:mb-2 prose-p:my-0 &#091;&amp;&gt;p&#093;:pt-0 &#091;&amp;&gt;p&#093;:mb-2 &#091;&amp;&gt;p&#093;:my-0\" style=\"box-sizing: border-box; scrollbar-color: initial; scrollbar-width: initial; --tw-border-spacing-x: 0; --tw-border-spacing-y: 0; --tw-translate-x: 0; --tw-translate-y: 0; --tw-rotate: 0; --tw-skew-x: 0; --tw-skew-y: 0; --tw-scale-x: 1; --tw-scale-y: 1; --tw-scroll-snap-strictness: proximity; --tw-ring-offset-width: 0px; --tw-ring-offset-color: #fff; --tw-ring-color: rgb(59 130 246 \/ .5); --tw-ring-offset-shadow: 0 0 #0000; --tw-ring-shadow: 0 0 #0000; --tw-shadow: 0 0 #0000; --tw-shadow-colored: 0 0 #0000; margin-top: 0px; margin-bottom: 0px; padding-inline-start: 0.375em; padding-top: 0px; padding-bottom: 0px; border: 0px solid oklch(var(--foreground-subtler-color));\">\n<p class=\"my-2 &#091;&amp;+p&#093;:mt-4 &#091;&amp;_strong:has(+br)&#093;:inline-block &#091;&amp;_strong:has(+br)&#093;:pb-2\">W przypadku jednoczesnego zam\u00f3wienia kilku Produkt\u00f3w, Sprzedawca mo\u017ce \u2013 po uzgodnieniu z Klientem \u2013 dokona\u0107 cz\u0119\u015bciowej wysy\u0142ki zam\u00f3wienia bez dodatkowych koszt\u00f3w po stronie Klienta, chyba \u017ce co innego wynika z ustale\u0144 z Klientem.<\/p>\n<\/li>\n<\/ol>\n<h3>\u00a7 VIII - Beschwerden und Streitbeilegung<\/h3>\n<p>(1) Es k\u00f6nnen Beschwerden eingereicht werden:<\/p>\n<p>a. schriftlich - pers\u00f6nlich bei der Gesellschaft oder per Post, Kurier oder Bote an die Adresse der Gesellschaft: ul.Jeleniog\u00f3rska 16, 60-179 Pozna\u0144;<\/p>\n<p>b. per E-Mail - \u00fcber kontakt@staviori.pl.<\/p>\n<p>c. m\u00fcndlich - telefonisch unter 500 744 070 von 10.00 bis 16.00 Uhr an Werktagen und von 10.00 bis 14.00 Uhr an Samstagen (der Anruf wird nach den Tarifen des f\u00fcr den Benutzer zust\u00e4ndigen Telekommunikationsbetreibers berechnet).<\/p>\n<p>(2) Die Beschwerde sollte eine Beschreibung des Problems und Kontaktangaben enthalten.<\/p>\n<p>(3) Die Beschwerde sollte eine kurze Beschreibung der gemeldeten Beanstandungen, die Vorgangsnummer und die Angabe der Daten des Nutzers zusammen mit seiner Postanschrift (z. B. Wohnanschrift) enthalten, es sei denn, der Nutzer hat seine Beschwerde \u00fcber das auf der Website verf\u00fcgbare Formular eingereicht: Der Nutzer hat eine Beschwerde unter Verwendung des auf der Website verf\u00fcgbaren Beschwerdeformulars eingereicht - in diesem Fall gibt der Nutzer in dem Formular die Postanschrift f\u00fcr die Zustellung der Antwort auf die Beschwerde an.<\/p>\n<p>(4) Auf Verlangen des Nutzers best\u00e4tigt das Unternehmen dem Nutzer den Eingang der Beschwerde per E-Mail oder schriftlich.<\/p>\n<p>(5) Das Unternehmen pr\u00fcft die Beschwerde unverz\u00fcglich, sp\u00e4testens jedoch innerhalb von 14 Arbeitstagen nach Eingang.<\/p>\n<p>(6) In besonders komplizierten F\u00e4llen, die eine Pr\u00fcfung der Beschwerde und eine Beantwortung innerhalb der in Absatz (5) genannten Frist unm\u00f6glich machen, erl\u00e4utert das Unternehmen dem Nutzer die Gr\u00fcnde f\u00fcr die Verz\u00f6gerung, gibt die Umst\u00e4nde an, die f\u00fcr die Pr\u00fcfung der Beschwerde festgestellt werden m\u00fcssen, und nennt die voraussichtliche Frist f\u00fcr die Pr\u00fcfung der Beschwerde und die Beantwortung, die nicht l\u00e4nger als 35 Arbeitstage ab dem Eingang der Beschwerde sein darf.<\/p>\n<p>(7) Wenn die Reklamation nach dem Wortlaut von Absatz 3 erg\u00e4nzt werden muss, fordert das Unternehmen den Nutzer auf, die Reklamation zu erg\u00e4nzen.<\/p>\n<p>(8) Die Antwort auf eine Beschwerde wird in Papierform an die auf dem Formular angegebene Postanschrift gesandt oder, falls der Nutzer um eine Antwort per E-Mail gebeten hat, an die vom Nutzer angegebene E-Mail-Adresse.<\/p>\n<p>(9) Der Nutzer sollte bedenken, dass die Einreichung einer Beschwerde, sobald der Nutzer einen Einwand erhoben hat, eine faire Bearbeitung der Beschwerde durch das Unternehmen erleichtern und beschleunigen kann.<\/p>\n<p>(10) Das Beschwerdeverfahren schlie\u00dft die Rechte des Nutzers nach dem Gesetz nicht aus.<\/p>\n<p>(11) Der Nutzer hat das Recht, das Unternehmen vor einem ordentlichen Gericht zu verklagen. Zust\u00e4ndig f\u00fcr Streitigkeiten aus diesem Vertrag ist das nach den Bestimmungen der Zivilprozessordnung zust\u00e4ndige Gericht (in der Regel das f\u00fcr den Sitz des Unternehmens zust\u00e4ndige Gericht).<\/p>\n<p>(12) Ein Nutzer, der Verbraucher ist, kann sich auch an die au\u00dfergerichtliche Streitbeilegung wenden, insbesondere an die st\u00e4ndigen Verbraucherschlichtungsstellen bei den Provinzialinspektionen der Gewerbeaufsicht. Informationen zur g\u00fctlichen Streitbeilegung finden Sie unter http:\/\/www.polubowne.uokik.gov.pl\/.<\/p>\n<p>(13) Ist der Nutzer ein Verbraucher, hat er auch die M\u00f6glichkeit, sich an den zust\u00e4ndigen Verbraucher-Ombudsmann und das ODR zu wenden.<\/p>\n<p>14. W przypadku uznania reklamacji Klienta dotycz\u0105cej towaru lub us\u0142ugi, Sp\u00f3\u0142ka \u2013 zgodnie z wyborem Klienta wynikaj\u0105cym z obowi\u0105zuj\u0105cych przepis\u00f3w \u2013 mo\u017ce w szczeg\u00f3lno\u015bci:<br \/>\u00a0 \u00a0a. naprawi\u0107 towar,<br \/>\u00a0 \u00a0b. wymieni\u0107 towar na wolny od wad,<br \/>\u00a0 \u00a0c. obni\u017cy\u0107 cen\u0119,<br \/>\u00a0 \u00a0d. odst\u0105pi\u0107 od umowy i dokona\u0107 zwrotu pe\u0142nej zap\u0142aconej kwoty.<\/p>\n<p>15. W przypadku odst\u0105pienia od umowy z powodu uznanej reklamacji, Sp\u00f3\u0142ka zwraca Klientowi wszystkie otrzymane od niego p\u0142atno\u015bci zwi\u0105zane z dan\u0105 umow\u0105, w tym cen\u0119 Produktu oraz koszty pierwotnej dostawy do Klienta (w wysoko\u015bci odpowiadaj\u0105cej najta\u0144szemu zwyk\u0142emu sposobowi dostawy oferowanemu w Serwisie), nie p\u00f3\u017aniej ni\u017c w terminie 14 dni od dnia pozytywnego rozpatrzenia reklamacji lub otrzymania od Klienta zwracanego Produktu \u2013 w zale\u017cno\u015bci od tego, kt\u00f3re zdarzenie nast\u0105pi p\u00f3\u017aniej. Zwrot p\u0142atno\u015bci nast\u0119puje przy u\u017cyciu takiego samego sposobu zap\u0142aty, jakiego u\u017cy\u0142 Klient, chyba \u017ce wyra\u017anie zgodzi\u0142 si\u0119 on na inny spos\u00f3b zwrotu, niewi\u0105\u017c\u0105cy si\u0119 dla niego z \u017cadnymi kosztami.<\/p>\n<h3>\u00a7 IX - Kommunikation und technische Anforderungen<\/h3>\n<p>Die Sprache, in der das Unternehmen mit dem Nutzer kommuniziert und den Vertrag abschlie\u00dft, ist Polnisch.<\/p>\n<p>(2) Soweit in diesen Gesch\u00e4ftsbedingungen, insbesondere in \u00a7 VIII (Beschwerden und Streitbeilegung), nichts anderes bestimmt ist, kann der Nutzer mit dem Unternehmen kommunizieren:<\/p>\n<p>a. elektronisch, per E-Mail an kontakt@staviori.pl;<\/p>\n<p>b. telefonisch unter 500 744 070 - w\u00e4hrend der Gesch\u00e4ftszeiten der Dienststelle;<\/p>\n<p>c. schriftlich an INFINITY Dawid Namy\u015blak, ul.Jeleniog\u00f3rska 16, 60-179 Pozna\u0144.<\/p>\n<p>(3) Das Unternehmen kommuniziert mit dem Nutzer vorbehaltlich \u00a7 VIII (Reklamationen und Streitbeilegung) elektronisch, telefonisch oder schriftlich, wobei die Kommunikation mit dem Nutzer vorrangig per E-Mail erfolgt, sofern sich aus den Bestimmungen der AGB oder dem Gesetz nichts anderes ergibt.<\/p>\n<p>(4) Die auf der Grundlage dieser Bedingungen erbrachten Leistungen werden elektronisch \u00fcber das Internet erbracht. Um den Vertrag abschlie\u00dfen und die Dienste nutzen zu k\u00f6nnen, muss der Nutzer die folgenden technischen Voraussetzungen erf\u00fcllen:<\/p>\n<p>(a) \u00fcber ein Ger\u00e4t mit Internetanschluss und einem Speicher zur Speicherung von Dokumenten in elektronischer Form verf\u00fcgen (z. B. einen Computer oder ein Mobiltelefon)<\/p>\n<p>(b) \u00fcber einen Internet-Browser zu verf\u00fcgen, der in der Lage ist, die Website korrekt darzustellen, einschlie\u00dflich des Herunterladens und Speicherns von Dokumenten in elektronischer Form;<\/p>\n<p>(c) \u00fcber eine Software verf\u00fcgen, die Dokumente im PDF-Format korrekt anzeigen kann;<\/p>\n<p>(d) ein aktives E-Mail-Konto;<\/p>\n<p>e) f\u00fcr bestimmte Dienstleistungen ein Bankkonto mit Online-Zugang bei einem Unternehmen, das in der Liste der vom Unternehmen unterst\u00fctzten Zahlungsmethoden aufgef\u00fchrt ist, oder eine Zahlungskarte oder ein anderes vom Unternehmen unterst\u00fctztes Zahlungsinstrument besitzen (die aktuelle Liste der vom Unternehmen unterst\u00fctzten Zahlungsmethoden wird dem Nutzer auf der Website angezeigt).<\/p>\n<p>(5) Der Nutzer tr\u00e4gt die Kosten f\u00fcr den Internetzugang und die Daten\u00fcbertragung gem\u00e4\u00df dem Tarif seines Betreibers.<\/p>\n<p>(6) Das Unternehmen haftet nicht f\u00fcr Handlungen Dritter, auf deren Auswahl der Nutzer keinen Einfluss hat (z.B. Telekommunikationsbetreiber, Internetprovider oder Anbieter von schnellen Zahlungsdiensten).<\/p>\n<h3>\u00a7 X - G\u00fcltigkeit, K\u00fcndigung, \u00c4nderung und R\u00fccktritt vom Kundenvertrag<\/h3>\n<p>1 Der Vertrag wird \u00fcber den Dienst abgeschlossen und beendet.<\/p>\n<p>(2) Die Website des Shops stellt kein Angebot im Sinne des B\u00fcrgerlichen Gesetzbuches dar, sondern eine Aufforderung zur Abgabe eines Angebots. Durch die Bestellung von Waren gibt der Kunde ein Angebot zum Abschluss eines Vertrages ab. Nach der Bestellung erh\u00e4lt der Kunde unverz\u00fcglich eine automatisch generierte Nachricht an die von ihm angegebene E-Mail-Adresse, in der best\u00e4tigt wird, dass der Shop die Bestellung erhalten hat. Der Kaufvertrag kommt mit dem Erhalt einer E-Mail-Nachricht des Shops zustande, die besagt, dass die Bestellung zur Ausf\u00fchrung angenommen worden ist. Diese Nachricht ist gleichbedeutend mit der Annahme des vom Kunden abgegebenen Angebots durch den Verk\u00e4ufer. Wir sind berechtigt, eine Auftragsbest\u00e4tigung zu widerrufen, wenn unsere Online-Pr\u00e4sentation oder Auftragsbest\u00e4tigung Fehler oder Unrichtigkeiten enth\u00e4lt, die sich zu unserem Nachteil auf den Vertragsinhalt auswirken (z.B. unbeabsichtigte Abweichungen von aktuellen Marktpreisen aufgrund fehlerhafter Datenverarbeitung). In diesem Fall werden wir innerhalb einer Woche nach Entdeckung des Fehlers eine Erkl\u00e4rung \u00fcber den Widerruf der Best\u00e4tigung abgeben (z.B. per E-Mail) und den ggf. bereits gezahlten Kaufpreis zuz\u00fcglich etwaiger Mehrkosten unverz\u00fcglich erstatten. Unsere gesetzlichen Rechte, insbesondere das Recht zur Anfechtung des Vertrages wegen Irrtums, bleiben hiervon unber\u00fchrt.<\/p>\n<p>(3) Der Verbraucher hat das Recht, den Vertrag innerhalb von 14 Tagen ohne Angabe von Gr\u00fcnden - nach Ma\u00dfgabe der gesetzlichen Bestimmungen - zu widerrufen.<\/p>\n<p>(4) Der Kunde hat die Ware innerhalb von 14 Tagen nach Erkl\u00e4rung des Widerrufs zur\u00fcckzugeben.<\/p>\n<p>(5) Die im vorstehenden Absatz genannte R\u00fccktrittserkl\u00e4rung kann u. a. schriftlich per Post\/Kurierdienst oder elektronisch an die Gesellschaft unter folgender Adresse \u00fcbermittelt werden: kontakt@staviori.pl.<\/p>\n<p>6 Die R\u00fccksendung des Produkts sollte alle Bestandteile des Produkts enthalten, einschlie\u00dflich Verpackung, Zertifikat, Kaufnachweis usw.<\/p>\n<p>(7) Dem Verbraucher steht bei einem Fernabsatzvertrag kein Widerrufsrecht zu, wenn es sich bei dem Leistungsgegenstand um einen nicht vorgefertigten Gegenstand handelt, der nach den individuellen Spezifikationen des Verbrauchers angefertigt wurde oder der den pers\u00f6nlichen Bed\u00fcrfnissen des Verbrauchers entspricht.<\/p>\n<p>8 HINWEIS!!! Bei Produkten, die auf individuelle Kundenbestellung hergestellt werden, ist eine Vorauszahlung von 30% des Produktwerts erforderlich, um die Bestellung abzuschlie\u00dfen. Diese Vorauszahlung stellt eine Anzahlung im Sinne des B\u00fcrgerlichen Gesetzbuches dar und wird nicht zur\u00fcckerstattet, wenn der Kunde den Kauf storniert!<\/p>\n<p>9 Der Kunde tr\u00e4gt die unmittelbaren Kosten der R\u00fccksendung der Waren.<\/p>\n<p>(10) Der Verk\u00e4ufer hat den Kaufpreis innerhalb von 14 Tagen nach R\u00fcckerhalt der Ware bzw. nach \u00dcbergabe des Nachweises der R\u00fccksendung durch den Kunden, je nachdem, welches Ereignis zuerst eintritt, auf das vom Kunden angegebene Bankkonto zu \u00fcberweisen.<\/p>\n<p>(11) Die Vorschriften \u00fcber Kautionen bei Sonderanfertigungen richten sich nach dem B\u00fcrgerlichen Gesetzbuch.<\/p>\n<h3>\u00a7 XI - G\u00fcltigkeit, K\u00fcndigung, \u00c4nderung und R\u00fccktritt von der Partnervereinbarung<\/h3>\n<p>(1) Der Kooperationsvertrag wird in schriftlicher Form geschlossen und beendet und als Vertriebsvertrag bezeichnet.<\/p>\n<p>(2) Ein Vertriebsvertrag kommt zustande, wenn er unterzeichnet und elektronisch als Scan oder per Post versandt wird.<\/p>\n<p>3. die Vertriebsvereinbarung erm\u00f6glicht den Kauf von Waren zu einem Gro\u00dfhandelsrabatt bei staviori.eu<\/p>\n<p>(4) Der Partner hat das Recht, die gekaufte Ware innerhalb einer Frist von maximal 30 Tagen ab dem Datum der Bestellung zur\u00fcckzugeben.<\/p>\n<p>5 Die R\u00fcckerstattung f\u00fcr zur\u00fcckgesandte Waren ist an die Zustellung einer unterzeichneten Korrekturrechnung an die registrierte Adresse des Unternehmens gebunden.<\/p>\n<p>6 Der Partner tr\u00e4gt die unmittelbaren Kosten der R\u00fccksendung der Waren.<\/p>\n<p>(7) Der Partner hat kein Widerrufsrecht bei einem im Fernabsatz geschlossenen Vertrag, dessen Leistungsgegenstand eine nicht vorgefertigte, nach individuellen Vorgaben hergestellte Sache ist. Die Information, ob es sich um eine Sonderanfertigung handelt, erscheint bei jeder Bestellung eines Produkts.<\/p>\n<p>(8) Bei Sonderanfertigungen ist - je nach individueller Absprache bei Auftragserteilung - eine Vorauszahlung in H\u00f6he des Gesamtbetrages oder mindestens 30% des Warenwertes erforderlich, um den Auftrag auszuf\u00fchren. Diese Vorauszahlung stellt eine Anzahlung im Sinne des B\u00fcrgerlichen Gesetzbuches dar und wird nicht zur\u00fcckerstattet, wenn der Partner den Kauf storniert!<\/p>\n<p>(9) Der Vertriebsvertrag kann nur schriftlich gek\u00fcndigt werden.<\/p>\n<p>10 Das Unternehmen erkl\u00e4rt, dass alle Kundendaten, die es im Rahmen der Zusammenarbeit von den Partnern erh\u00e4lt, nur zum Zwecke der Abwicklung der Bestellung und des Versands der Ware in Form des \"Dropshipping\" gesichert und verarbeitet und anschlie\u00dfend gel\u00f6scht werden. Verantwortlich f\u00fcr die Daten bleibt demnach grunds\u00e4tzlich der Online-Shop, bei dem der Kunde die Ware bestellt, d.h. der Partner.<\/p>\n<h3>\u00a7 XII - Schlussbestimmungen<\/h3>\n<p>(1) Der Vertrag unterliegt dem polnischen Recht.<\/p>\n<p>(2) Die Bestimmungen k\u00f6nnen jederzeit ge\u00e4ndert werden. \u00c4nderungen der Gesch\u00e4ftsbedingungen sind ab dem Zeitpunkt ihrer Ver\u00f6ffentlichung auf der Website www.staviori.com.pl wirksam.<\/p>\n<p>(3) \u00c4nderungen haben keine nachteiligen Auswirkungen auf die Rechte und Pflichten des Nutzers in Bezug auf die bereits erbrachten Leistungen. Alle Nutzerdaten der Website www.staviori.pl sind vertraulich und werden nicht weitergegeben oder f\u00fcr andere Zwecke als die direkte Abwicklung der Bestellung verwendet.<\/p>\n<p>(4) In Angelegenheiten, die in diesen Vorschriften nicht geregelt sind, gilt das Recht der Republik Polen.<\/p>\n<p>5 Wenn Sie Anmerkungen zum Funktionieren des Dienstes, zur Darstellung und Zuverl\u00e4ssigkeit der Daten oder zu festgestellten Unregelm\u00e4\u00dfigkeiten haben oder wenn Sie Fragen zu personenbezogenen Daten und zur Aus\u00fcbung Ihrer Datenschutzrechte haben, wenden Sie sich bitte an den Datenschutzbeauftragten: Adresse: Jeleniog\u00f3rska 16 60-179 Pozna\u0144, PL E-Mail: iodo@staviori.pl.<\/p>\n<p>6 Wir m\u00f6chten Sie darauf hinweisen, dass bei Aktionsartikeln der Aktionspreis immer gleichzeitig der niedrigste Preis der letzten 30 Tage ist, d.h. der sogenannte Omnibus-Preis. Wir wenden in dieser Hinsicht keine unlauteren Praktiken an. Wir unterbieten die Preise vor den Werbeaktionen (Omnibus) nicht.<\/p>\n<h3>\u00a0<\/h3>\n<h2>Allgemeine Gesch\u00e4ftsbedingungen f\u00fcr den Zusatzdienst - Newsletter<\/h2>\n<div><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/staviori.pl\/images\/linia_horyzontalna_300x5.jpg\" width=\"486\" height=\"9\" \/><\/div>\n<h3>\u00a0<\/h3>\n<p>Gem\u00e4\u00df Artikel 8 Absatz 1 des Gesetzes vom 18. Juli 2002 \u00fcber die Erbringung von Dienstleistungen auf elektronischem Wege (Gesetzblatt 2013, Pos. 1422) ver\u00f6ffentlicht INFINITY Dawid Namy\u015blak, nachstehend Infinity genannt, im Folgenden die Newsletter-Verordnung:<\/p>\n<p>1 Der kostenlose Newsletter-Service wird von Infinity unter den Bedingungen dieser Bestimmungen angeboten. Bitte lesen Sie diese Bedingungen sorgf\u00e4ltig durch, bevor Sie sich zur Nutzung des Newsletter-Dienstes anmelden.<\/p>\n<p>(2) F\u00fcr die Nutzung des Dienstes sind ein Computer mit Internetzugang, ein beliebiger Internet-Browser sowie eine aktive und korrekt konfigurierte E-Mail erforderlich.<\/p>\n<p>Der 3. Newsletter ist ein kostenloser Service, der die Nutzer \u00fcber Aktionen, Wettbewerbe, Veranstaltungen, Neuigkeiten und Kollektionen von Infinity informiert, indem er regelm\u00e4\u00dfig von der Redaktion ausgew\u00e4hlte Inhalte in Form eines elektronischen Briefes versendet.<\/p>\n<p>Das Abonnement des Newsletters besteht aus der Eingabe der E-Mail-Adresse des Nutzers in ein von Infinity auf der Website bereitgestelltes Formular. Mit dem Abonnement des Newsletters erkl\u00e4rt der Nutzer sein Einverst\u00e4ndnis zum Erhalt eines kostenlosen Newsletters.<\/p>\n<p>5. Infinity wird die ihr anvertrauten E-Mail-Adressen nicht an Dritte weitergeben.<\/p>\n<p>6 Der Nutzer hat das Recht, den Newsletter-Service jederzeit abzubestellen. Sie k\u00f6nnen Ihr Abonnement k\u00fcndigen, indem Sie auf den Link \"Abbestellen\" am Ende jeder E-Mail klicken.<\/p>\n<p>7 Die L\u00f6schung des E-Mail-Kontos des Nutzers aus der Newsletter-Adressdatenbank erfolgt unverz\u00fcglich und wird durch eine Best\u00e4tigungsnachricht signalisiert.<\/p>\n<p>(8) Mit dem Abonnement des Newsletters erkl\u00e4rt sich der Kunde damit einverstanden, dass Infinity \u00fcber den Newsletter Werbung und kommerzielle Informationen im Sinne des Gesetzes vom 18. Juli 2002 \u00fcber die Erbringung elektronischer Dienstleistungen (Gesetzblatt 2013, Art. 1422) an das E-Mail-Konto des Nutzers sendet.<\/p>\n<p>9 Infinity beh\u00e4lt sich das Recht vor, ein Konto zu l\u00f6schen, dessen Nutzer gegen die vorliegenden Bestimmungen oder das in der Republik Polen geltende Recht versto\u00dfen hat oder Handlungen vornimmt, die die ungest\u00f6rte Nutzung des Dienstes durch andere Nutzer beeintr\u00e4chtigen oder illegale Inhalte bereitstellt.<\/p>\n<\/div>\n\t\t\n<style>\n#text-3284599391 {\n  font-size: 0.95rem;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_244881354 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-9329","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"iGGPvpWDjZN1_r6YkwnutzmmQsvPyvuVoKdFILjCIto\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/staviori.pl\/de\/regulamin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Staviori - Pier\u015bcionek Zar\u0119czynowy z Brylantem, Diamentem, Szafirem...\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Regulamin - Staviori\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/staviori.pl\/de\/regulamin\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-04-26T17:43:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-21T11:45:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Regulamin - Staviori\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/regulamin\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staviori.pl\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/regulamin\\\/#listItem\",\"name\":\"Regulamin\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/regulamin\\\/#listItem\",\"position\":2,\"name\":\"Regulamin\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/#organization\",\"name\":\"Staviori\",\"description\":\"Pier\\u015bcionek Zar\\u0119czynowy z Brylantem, Diamentem, Szafirem...\",\"url\":\"https:\\\/\\\/staviori.pl\\\/de\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/regulamin\\\/#webpage\",\"url\":\"https:\\\/\\\/staviori.pl\\\/de\\\/regulamin\\\/\",\"name\":\"Regulamin - Staviori\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/regulamin\\\/#breadcrumblist\"},\"datePublished\":\"2023-04-26T19:43:55+02:00\",\"dateModified\":\"2026-01-21T12:45:33+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/staviori.pl\\\/de\\\/\",\"name\":\"Staviori\",\"description\":\"Pier\\u015bcionek Zar\\u0119czynowy z Brylantem, Diamentem, Szafirem...\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/staviori.pl\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Regulamin - Staviori","description":"","canonical_url":"https:\/\/staviori.pl\/de\/regulamin\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"iGGPvpWDjZN1_r6YkwnutzmmQsvPyvuVoKdFILjCIto","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/staviori.pl\/de\/regulamin\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de#listItem","position":1,"name":"Home","item":"https:\/\/staviori.pl\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/regulamin\/#listItem","name":"Regulamin"}},{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de\/regulamin\/#listItem","position":2,"name":"Regulamin","previousItem":{"@type":"ListItem","@id":"https:\/\/staviori.pl\/de#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/staviori.pl\/de\/#organization","name":"Staviori","description":"Pier\u015bcionek Zar\u0119czynowy z Brylantem, Diamentem, Szafirem...","url":"https:\/\/staviori.pl\/de\/"},{"@type":"WebPage","@id":"https:\/\/staviori.pl\/de\/regulamin\/#webpage","url":"https:\/\/staviori.pl\/de\/regulamin\/","name":"Regulamin - Staviori","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/staviori.pl\/de\/#website"},"breadcrumb":{"@id":"https:\/\/staviori.pl\/de\/regulamin\/#breadcrumblist"},"datePublished":"2023-04-26T19:43:55+02:00","dateModified":"2026-01-21T12:45:33+01:00"},{"@type":"WebSite","@id":"https:\/\/staviori.pl\/de\/#website","url":"https:\/\/staviori.pl\/de\/","name":"Staviori","description":"Pier\u015bcionek Zar\u0119czynowy z Brylantem, Diamentem, Szafirem...","inLanguage":"de-DE","publisher":{"@id":"https:\/\/staviori.pl\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Staviori - Pier\u015bcionek Zar\u0119czynowy z Brylantem, Diamentem, Szafirem...","og:type":"article","og:title":"Regulamin - Staviori","og:url":"https:\/\/staviori.pl\/de\/regulamin\/","article:published_time":"2023-04-26T17:43:55+00:00","article:modified_time":"2026-01-21T11:45:33+00:00","twitter:card":"summary_large_image","twitter:title":"Regulamin - Staviori"},"aioseo_meta_data":{"post_id":"9329","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-05-17 18:22:55","updated":"2026-01-21 11:51:40","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/staviori.pl\/de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRegulamin\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/staviori.pl\/de"},{"label":"Regulamin","link":"https:\/\/staviori.pl\/de\/regulamin\/"}],"_links":{"self":[{"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/pages\/9329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/comments?post=9329"}],"version-history":[{"count":6,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/pages\/9329\/revisions"}],"predecessor-version":[{"id":22877,"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/pages\/9329\/revisions\/22877"}],"wp:attachment":[{"href":"https:\/\/staviori.pl\/de\/wp-json\/wp\/v2\/media?parent=9329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}